{"id":18306,"date":"2022-05-05T16:22:03","date_gmt":"2022-05-05T15:22:03","guid":{"rendered":"https:\/\/macoiffeuseafro.com\/blog\/?p=18306"},"modified":"2022-05-05T16:22:04","modified_gmt":"2022-05-05T15:22:04","slug":"tina-kunakey-mannequin-et-icone-de-beaute","status":"publish","type":"post","link":"/blog\/tina-kunakey-mannequin-et-icone-de-beaute\/","title":{"rendered":"Tina Kunakey : mannequin et ic\u00f4ne de beaut\u00e9"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Parmi ces <a rel=\"noreferrer noopener\" href=\"https:\/\/macoiffeuseafro.com\/blog\/oprah-winfrey-une-milliardaire-partie-de-rien\/\" data-type=\"URL\" data-id=\"https:\/\/macoiffeuseafro.com\/blog\/oprah-winfrey-une-milliardaire-partie-de-rien\/\" target=\"_blank\">success stories<\/a> qui n'ont cess\u00e9 de nous inspirer jusqu'aujourd'hui, nous n'avons pas pu passer \u00e0 c\u00f4t\u00e9 de celle de Tina Kunakey. Mannequin, \u00e9g\u00e9rie, ic\u00f4ne de beaut\u00e9... On vous dit tout sur la nouvelle \u00e9g\u00e9rie de Make Up Forever !<\/h2>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Une chose est s\u00fbre, la belle Tina n'a pas fini de faire parler d'elle. Apr\u00e8s avoir sublim\u00e9 <strong>les d\u00e9fil\u00e9s et les tapis rouges <\/strong>des plus grands noms de la haute couture et de la haute joaillerie, le mannequin n'est pas pass\u00e9 <strong>inaper\u00e7ue<\/strong> \u00e9galement aupr\u00e8s du grand public pour son allure et ses <strong><a rel=\"noreferrer noopener\" href=\"https:\/\/macoiffeuseafro.com\/blog\/top-3-des-meilleures-adresses-specialistes-des-cheveux-afros-a-paris\/\" data-type=\"URL\" data-id=\"https:\/\/macoiffeuseafro.com\/blog\/top-3-des-meilleures-adresses-specialistes-des-cheveux-afros-a-paris\/\" target=\"_blank\">looks sensationnels<\/a><\/strong>. Mannequin et ic\u00f4ne de beaut\u00e9, mais alors qui est r\u00e9ellement celle \u00e0 qui tout r\u00e9ussi ?<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Des d\u00e9buts prometteurs<\/strong><\/h3>\n\n\n\n<p>Originaire de Toulouse, la jeune femme passe une majeure partie de sa jeunesse sur la c\u00f4te basque. Elle devient tr\u00e8s vite convoit\u00e9e pour <strong>repr\u00e9senter plusieurs marques<\/strong> telles que <em>Quicksilver <\/em>ou <em>Roxy<\/em>. Si \u00e0 l'\u00e9poque ses parents s'opposaient \u00e0 ce que la jeune Tina parte \u00e0 l'\u00e9tranger pour poursuivre sa <strong><a rel=\"noreferrer noopener\" href=\"https:\/\/macoiffeuseafro.com\/blog\/comment-virgil-abloh-a-t-il-revolutionne-le-monde-de-la-mode\/\" data-type=\"URL\" data-id=\"https:\/\/macoiffeuseafro.com\/blog\/comment-virgil-abloh-a-t-il-revolutionne-le-monde-de-la-mode\/\" target=\"_blank\">carri\u00e8re<\/a><\/strong>, elle finit par les convaincre et \u00e0 travailler dans l'univers du<strong> mannequinat et de l'audiovisuel<\/strong>. Il y a 6 ans, on la remarque pour la premi\u00e8re fois en tant que figurante pour le clip <strong>Danj\u00e9<\/strong> de l'artiste Martiniquais <em>Kalash<\/em>.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/macoiffeuseafro.com\/blog\/wp-content\/uploads\/2022\/05\/Capture-de\u0301cran-2022-05-03-a\u0300-13.37.26.png\" alt=\"Tina Kunakey : mannequin et ic\u00f4ne de beaut\u00e9\" class=\"wp-image-18314\" width=\"381\" height=\"463\" srcset=\"/blog\/wp-content\/uploads\/2022\/05\/Capture-de\u0301cran-2022-05-03-a\u0300-13.37.26.png 452w, /blog\/wp-content\/uploads\/2022\/05\/Capture-de\u0301cran-2022-05-03-a\u0300-13.37.26-247x300.png 247w, /blog\/wp-content\/uploads\/2022\/05\/Capture-de\u0301cran-2022-05-03-a\u0300-13.37.26-400x487.png 400w, /blog\/wp-content\/uploads\/2022\/05\/Capture-de\u0301cran-2022-05-03-a\u0300-13.37.26-411x500.png 411w\" sizes=\"auto, (max-width: 381px) 100vw, 381px\" \/><figcaption>@tinakunakey<\/figcaption><\/figure><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Carri\u00e8re dans le mannequinat<\/strong><\/h3>\n\n\n\n<p>D'origine togolaise et sicilienne \u00e0 seulement 25 ans sa carri\u00e8re est beau fixe. Entre <strong><a rel=\"noreferrer noopener\" href=\"https:\/\/macoiffeuseafro.com\/blog\/kaliegh-garris-couronnee-miss-teen-usa-2019-afro\/\" data-type=\"URL\" data-id=\"https:\/\/macoiffeuseafro.com\/blog\/kaliegh-garris-couronnee-miss-teen-usa-2019-afro\/\" target=\"_blank\">tapis rouges et d\u00e9fil\u00e9s<\/a><\/strong>, Tina Kunakey encha\u00eene les succ\u00e8s. \u00c0 l'\u00e2ge de 15 ans, elle d\u00e9croche<strong> son premier contrat<\/strong> dans l'agence espagnole <em>Mad Model Management<\/em> \u00e0 <strong>Madrid<\/strong>. Quelques temps apr\u00e8s, elle s'envole pour <strong>Londres<\/strong> afin de rejoindre le tournage d'un court-m\u00e9trage au sein de l'agence <em>SUPA Model Management<\/em> aux c\u00f4t\u00e9s du rappeur <strong>A$ap Rocky.<\/strong> V\u00e9ritable <strong><a rel=\"noreferrer noopener\" href=\"https:\/\/macoiffeuseafro.com\/blog\/on-vous-devoile-tous-les-secrets-beaute-de-la-routine-dhalle-berry\/\" data-type=\"URL\" data-id=\"https:\/\/macoiffeuseafro.com\/blog\/on-vous-devoile-tous-les-secrets-beaute-de-la-routine-dhalle-berry\/\" target=\"_blank\">beaut\u00e9<\/a><\/strong>, elle n'a pas laiss\u00e9 indiff\u00e9rent la <strong>prestigieuse agence <\/strong><em>IMG Models<\/em> qu'elle int\u00e8gre d\u00e8s son retour \u00e0 <strong><a rel=\"noreferrer noopener\" href=\"https:\/\/macoiffeuseafro.com\/blog\/top-3-des-meilleures-adresses-specialistes-des-cheveux-afros-a-paris\/\" data-type=\"URL\" data-id=\"https:\/\/macoiffeuseafro.com\/blog\/top-3-des-meilleures-adresses-specialistes-des-cheveux-afros-a-paris\/\" target=\"_blank\">Paris<\/a><\/strong>. On la retrouve \u00e9galement sur la couvertures de grands magazines tels que <strong>Marie-Claire, Vanity Fair, ELLE<\/strong>... carton plein pour la <strong>maman de la petite Amazonie<\/strong> !<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/macoiffeuseafro.com\/blog\/wp-content\/uploads\/2022\/05\/Capture-de\u0301cran-2022-05-03-a\u0300-13.33.45.png\" alt=\"Tina Kunakey : mannequin et ic\u00f4ne de beaut\u00e9\" class=\"wp-image-18325\" width=\"295\" height=\"356\" srcset=\"/blog\/wp-content\/uploads\/2022\/05\/Capture-de\u0301cran-2022-05-03-a\u0300-13.33.45.png 502w, /blog\/wp-content\/uploads\/2022\/05\/Capture-de\u0301cran-2022-05-03-a\u0300-13.33.45-249x300.png 249w, /blog\/wp-content\/uploads\/2022\/05\/Capture-de\u0301cran-2022-05-03-a\u0300-13.33.45-400x483.png 400w, /blog\/wp-content\/uploads\/2022\/05\/Capture-de\u0301cran-2022-05-03-a\u0300-13.33.45-414x500.png 414w\" sizes=\"auto, (max-width: 295px) 100vw, 295px\" \/><figcaption>@tinakunakey<\/figcaption><\/figure><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>3 coiffures protectrices rep\u00e9r\u00e9es sur Tina Kunakey<\/strong><\/h3>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>S'il y a bien une chose dont on ne se lasse pas, ce sont les diff\u00e9rentes <strong><a rel=\"noreferrer noopener\" href=\"https:\/\/macoiffeuseafro.com\/blog\/printemps-2021-5-coiffures-a-adopter\/\" data-type=\"URL\" data-id=\"https:\/\/macoiffeuseafro.com\/blog\/printemps-2021-5-coiffures-a-adopter\/\" target=\"_blank\">mises en beaut\u00e9<\/a><\/strong> que la femme de<strong> Vincent Cassel<\/strong> s'approprie \u00e0 merveille et d'autant plus ces derniers temps ! La belle n'a cess\u00e9 d'enflammer la toile avec des <strong>looks hors du commun<\/strong>. On vous laisse avec ces sublimes <strong>coiffures protectrices<\/strong> devenues de v\u00e9ritables coups de coeur : <\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Cornrows :<\/strong> Facile et l\u00e9g\u00e8re \u00e0 porter, cette coiffure prot\u00e8ge vos cheveux tout en leur donnant cet aspect soign\u00e9. Il s'agit de la <strong><a href=\"https:\/\/macoiffeuseafro.com\/blog\/cheveux-naturels-quelle-coiffure-realisee\/\" data-type=\"URL\" data-id=\"https:\/\/macoiffeuseafro.com\/blog\/cheveux-naturels-quelle-coiffure-realisee\/\" target=\"_blank\" rel=\"noreferrer noopener\">coiffure protectrice <\/a><\/strong>par excellence. <\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Jumbo Braids :<\/strong> Originale et facile \u00e0 r\u00e9aliser, ces tresses \u00e9paisses sont id\u00e9ales pour les amateurs de looks audacieux.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Braided Bun<\/strong> : Cette coiffure protectrice est l'alternative id\u00e9ale pour une mise en beaut\u00e9 unique tout en<strong> <a href=\"https:\/\/macoiffeuseafro.com\/blog\/decouvrez-la-nouvelle-huile-de-soin-fortifiante-in-haircare\/\" data-type=\"URL\" data-id=\"https:\/\/macoiffeuseafro.com\/blog\/decouvrez-la-nouvelle-huile-de-soin-fortifiante-in-haircare\/\">prot\u00e9geant vos cheveux <\/a><\/strong>d\u00e8s la racine.<\/li><\/ul>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/macoiffeuseafro.com\/blog\/wp-content\/uploads\/2022\/05\/BLOG-MCA-COVER-2.png\" alt=\"Tina Kunakey : mannequin et ic\u00f4ne de beaut\u00e9\" class=\"wp-image-18321\" width=\"517\" height=\"339\" srcset=\"/blog\/wp-content\/uploads\/2022\/05\/BLOG-MCA-COVER-2.png 640w, /blog\/wp-content\/uploads\/2022\/05\/BLOG-MCA-COVER-2-300x197.png 300w, /blog\/wp-content\/uploads\/2022\/05\/BLOG-MCA-COVER-2-400x263.png 400w\" sizes=\"auto, (max-width: 517px) 100vw, 517px\" \/><figcaption>@tinakunakey<\/figcaption><\/figure>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>Et vous, quel est votre look pr\u00e9f\u00e9r\u00e9 ?<\/strong> \ud83d\ude0d<\/h5>\n\n\n\n<p>Image de couverture Instagram : @tinakunakey<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Parmi ces success stories qui n&rsquo;ont cess\u00e9 de nous inspirer jusqu&rsquo;aujourd&rsquo;hui, nous n&rsquo;avons pas pu passer \u00e0 c\u00f4t\u00e9 de celle de Tina Kunakey. Mannequin, \u00e9g\u00e9rie, ic\u00f4ne de beaut\u00e9&#8230; On vous dit tout sur la nouvelle \u00e9g\u00e9rie de Make Up Forever ! Une chose est s\u00fbre, la belle Tina n&rsquo;a pas fini de faire parler d&rsquo;elle. Apr\u00e8s avoir sublim\u00e9 les d\u00e9fil\u00e9s et les tapis rouges des plus grands noms de la haute couture et de la haute joaillerie, le mannequin n&rsquo;est pas pass\u00e9 inaper\u00e7ue \u00e9galement aupr\u00e8s du grand public pour son allure et ses looks sensationnels. Mannequin et ic\u00f4ne de beaut\u00e9, [&hellip;]<\/p>\n","protected":false},"author":52,"featured_media":18309,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"yst_prominent_words":[13378,166,139,4620,13228,76,4065,1769,8562,13379,5917,12880,6262,1227,4036,13387,492,13381,6258,5930],"class_list":["post-18306","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-empowerment"],"_links":{"self":[{"href":"/blog\/wp-json\/wp\/v2\/posts\/18306","targetHints":{"allow":["GET"]}}],"collection":[{"href":"/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"/blog\/wp-json\/wp\/v2\/users\/52"}],"replies":[{"embeddable":true,"href":"/blog\/wp-json\/wp\/v2\/comments?post=18306"}],"version-history":[{"count":0,"href":"/blog\/wp-json\/wp\/v2\/posts\/18306\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"/blog\/wp-json\/wp\/v2\/media\/18309"}],"wp:attachment":[{"href":"/blog\/wp-json\/wp\/v2\/media?parent=18306"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"/blog\/wp-json\/wp\/v2\/categories?post=18306"},{"taxonomy":"post_tag","embeddable":true,"href":"/blog\/wp-json\/wp\/v2\/tags?post=18306"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"/blog\/wp-json\/wp\/v2\/yst_prominent_words?post=18306"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}